{"id":21659,"date":"2024-09-24T13:45:32","date_gmt":"2024-09-24T11:45:32","guid":{"rendered":"https:\/\/www.dataieanalytics.com\/politica-de-privacidad-copy\/"},"modified":"2025-07-22T13:33:37","modified_gmt":"2025-07-22T11:33:37","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"21659\" class=\"elementor elementor-21659\">\n\t\t\t\t<div class=\"elementor-element elementor-element-748bc6b e-flex e-con-boxed wcf-starter-animations-none e-con e-parent\" data-id=\"748bc6b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e5c7a8b e-con-full e-flex wcf-starter-animations-none e-con e-child\" data-id=\"e5c7a8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acc8282 elementor-widget__width-initial wcf-starter-animations-none wcf-t-animation-none elementor-widget elementor-widget-heading\" data-id=\"acc8282\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;bottom&quot;,&quot;data-duration&quot;:0.75,&quot;fade-offset&quot;:40,&quot;wcf_starter_animations&quot;:&quot;none&quot;,&quot;wcf_anim_duration&quot;:1000,&quot;wcf_anim_delay&quot;:0,&quot;wcf_anim_ease&quot;:&quot;ease&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;ease&quot;:&quot;power2.out&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90df7e8 e-flex e-con-boxed wcf-starter-animations-none e-con e-parent\" data-id=\"90df7e8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7a9714 wcf-starter-animations-none wcf-t-animation-none elementor-widget elementor-widget-text-editor\" data-id=\"c7a9714\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wcf_starter_animations&quot;:&quot;none&quot;,&quot;wcf_anim_duration&quot;:1000,&quot;wcf_anim_delay&quot;:0,&quot;wcf_anim_ease&quot;:&quot;ease&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;wcf-animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Con car\u00e1cter previo a la navegaci\u00f3n a trav\u00e9s de esta web, Ud. habr\u00e1 tenido la opci\u00f3n de autorizar el uso de todas o algunas cookies, o de rechazarlas o configurarlas mediante la informaci\u00f3n disponible en el aviso de cookies. En todo caso, le recordamos que Ud. puede rechazar las cookies en cualquier momento mediante su configuraci\u00f3n particular en el navegador que est\u00e9 utilizando.<\/p><p><strong><span style=\"color: #003366;\">1.\u00bfQu\u00e9 son las cookies y para qu\u00e9 se utilizan?<\/span><\/strong><\/p><p class=\"p1\">Las cookies son dispositivos de almacenamiento y recuperaci\u00f3n de datos del equipo terminal del usuario.<\/p><p class=\"p1\">La mayor parte de las cookies no aportan a ATTRIM Group datos identificativos directos de personas f\u00edsicas, sino de segmentos de usuarios. Sin embargo, las personas f\u00edsicas pueden ser asociadas a identificadores online facilitados por sus dispositivos; aplicaciones; herramientas; direcciones de protocolos de internet e identificadores de sesi\u00f3n a trav\u00e9s de nuestros formularios y de redes sociales (LinkedIn) que, combinadas con identificadores \u00fanicos, pueden utilizarse para identificar y distinguir un usuario de otros y realizar seguimiento.<\/p><p class=\"p1\">Las cookies permiten almacenar, actualizar y recuperar cierta informaci\u00f3n sobre el dispositivo o navegaci\u00f3n del usuario que puede ser utilizada para distintas finalidades, como por ejemplo, obtener informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n del usuario o de su equipo; ver qu\u00e9 p\u00e1ginas han sido visitadas; el tiempo de conexi\u00f3n; la ciudad a la que est\u00e1 asignada la direcci\u00f3n IP desde la que se accede; la frecuencia y reincidencia de las visitas; el tiempo de visita; el navegador o el operador o tipo de terminal desde el que se realiza la visita; analizar el funcionamiento de una p\u00e1gina; detectar problemas t\u00e9cnicos, etc.<\/p><p class=\"p1\">Cuando se utiliza nuestra web solo con fines informativos, los datos generales se almacenan inicialmente de forma autom\u00e1tica (es decir, no mediante registro) y su navegador los transmite a nuestro servidor. Por defecto, estos datos generales incluyen: El tipo y versi\u00f3n del navegador; el sistema operativo utilizado; la p\u00e1gina visitada; la p\u00e1gina visitada anteriormente (URL de referencia); la direcci\u00f3n IP; la fecha y hora de la solicitud del servidor y el c\u00f3digo de estado HTTP. El tratamiento de dichos datos tiene su base en el inter\u00e9s leg\u00edtimo de nuestra empresa, ya que dicha informaci\u00f3n se utiliza para la administraci\u00f3n t\u00e9cnica y seguridad de la web.<\/p><p><strong><span style=\"color: #003366;\">2. \u00bfQu\u00e9 tipos de cookies existen?<\/span><\/strong><\/p><p class=\"p1\">Las cookies pueden clasificarse en tres categor\u00edas:<\/p><p><span style=\"color: #003366;\"><strong>Seg\u00fan qui\u00e9n sea la entidad que gestione el dominio desde donde se env\u00edan las cookies y trate los datos que se obtengan:<\/strong><\/span><\/p><p><span style=\"color: #003366;\">Propias:<\/span> se env\u00edan al equipo terminal del usuario desde un equipo o dominio gestionado por el propio editor y desde el que se presta el servicio solicitado por el usuario.<\/p><p><span style=\"color: #003366;\">De terceros<\/span>: se env\u00edan al equipo terminal del usuario desde un equipo o dominio gestionado por un tercero distinto del editor o por el propio editor siendo el tercero quien trata los datos obtenidos trav\u00e9s de las cookies (por ejemplo, en el caso de esta web, la prestaci\u00f3n de servicios publicitarios a favor de otras entidades).<\/p><p><span style=\"color: #003366;\"><strong>Seg\u00fan el periodo de tiempo en el que permanecen activas en el equipo terminal:<\/strong><\/span><\/p><p><span style=\"color: #003366;\">De sesi\u00f3n:<\/span> recogen y almacenan informaci\u00f3n mientras el usuario accede a una web, aplicaci\u00f3n o herramienta para prestar el servicio solicitado por el usuario en una sola ocasi\u00f3n (por ejemplo, una lista de productos adquiridos) y desaparecen al terminar la sesi\u00f3n<\/p><p><span style=\"color: #003366;\">Permanentes:<\/span> los datos siguen almacenados en el terminal y pueden ser accedidos y tratados durante un periodo definido por el responsable de la cookie, y que puede ir de unos minutos a varios a\u00f1os.<\/p><p><span style=\"color: #003366;\"><strong>Seg\u00fan la finalidad para la que se traten los datos obtenidos:<\/strong><\/span><\/p><p><span style=\"color: #003366;\">T\u00e9cnicas:<\/span> (exentas) permiten la navegaci\u00f3n, gesti\u00f3n y operativa de una web, herramienta o aplicaci\u00f3n habilitar sus funciones y servicios (comunicaci\u00f3n de datos, identificar la sesi\u00f3n, acceder a partes de acceso restringido, recordar los elementos que integran un pedido, realizar el proceso de compra de un pedido, gestionar el pago, controlar el fraude vinculado a la seguridad del servicio, realizar la solicitud de inscripci\u00f3n o participaci\u00f3n en un evento, contar visitas a efectos de la facturaci\u00f3n de licencias del software con el que funciona el servicio, utilizar elementos de seguridad durante la navegaci\u00f3n, almacenar contenidos para la difusi\u00f3n de v\u00eddeos o sonido, habilitar contenidos din\u00e1micos (por ejemplo, animaci\u00f3n de carga de un texto o imagen) o compartir contenidos a trav\u00e9s de redes sociales;<\/p><p><span style=\"color: #003366;\">De personalizaci\u00f3n:<\/span> permiten recordar informaci\u00f3n para que el usuario acceda al servicio con determinadas caracter\u00edsticas que pueden diferenciar su experiencia de la de otros usuarios, (el idioma, el n\u00famero de resultados a mostrar cuando el usuario realiza una b\u00fasqueda, el aspecto o contenido del servicio en funci\u00f3n del tipo de navegador a trav\u00e9s del cual el usuario accede al servicio o de la regi\u00f3n desde la que accede al servicio, etc.). Si el usuario elige esas caracter\u00edsticas (por ejemplo, si selecciona el idioma clicando en el icono de la bandera del pa\u00eds correspondiente), estar\u00e1n exentas al considerarse un servicio expresamente solicitado por el usuario exclusivamente a la finalidad seleccionada;<\/p><p><span style=\"color: #003366;\">De an\u00e1lisis o estad\u00edstica de uso:<\/span> permiten cuantificar el n\u00famero de usuarios y realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios de los servicios ofertados a trav\u00e9s de esta web o de las de terceros que utilizan nuestros servicios, con el fin de introducir mejoras. Estas cookies no est\u00e1n exentas, aun cuando no representan un riesgo para la privacidad de los usuarios al no identificarles y tener una finalidad;<\/p><p><span style=\"color: #003366;\">Publicitarias:<\/span> aquellas que, tratadas por nosotros o por terceros, nos permiten analizar sus h\u00e1bitos de navegaci\u00f3n en Internet para que podamos mostrarle publicidad relacionada con su perfil de navegaci\u00f3n.<\/p><p><strong><span style=\"color: #003366;\">3. \u00bfPor qu\u00e9 es importante su consentimiento?<\/span><\/strong><\/p><p class=\"p1\">De conformidad con la normativa vigente, ATTRIM Group y las empresas de ATTRIM Group pueden instalar en los dispositivos de los usuarios cookies y tecnolog\u00edas similares, siempre que estos presten su consentimiento previa informaci\u00f3n clara y completa sobre las finalidades de su utilizaci\u00f3n. El objetivo de esta Pol\u00edtica es facilitar dicha informaci\u00f3n de un modo \u00fatil para el usuario.<\/p><p class=\"p1\">Sin embargo, algunas cookies est\u00e1n exentas de la obligaci\u00f3n de ser informadas. \u00c9stas son cookies que permiten la comunicaci\u00f3n entre el equipo del usuario y la red, as\u00ed como las que estrictamente prestan un servicio expresamente solicitado por el usuario, como, por ejemplo:<\/p><ul class=\"ul1\"><li class=\"li7\">Cookies de entrada del usuario, utilizadas para almacenar informaci\u00f3n del usuario al rellenar los formularios online que el usuario configura manteniendo la opci\u00f3n de autocompletar o guardar datos para ulteriores ocasiones.<\/li><li class=\"li7\">Cookies de seguridad del usuario utilizadas para detectar ataques de denegaci\u00f3n de servicio mediante intentos err\u00f3neos y reiterados de conexi\u00f3n a una web.<\/li><li class=\"li7\">Cookies de sesi\u00f3n para equilibrar la carga.<\/li><li class=\"li7\">Cookies de personalizaci\u00f3n de la interfaz de usuario.<\/li><li class=\"li7\">Cookies de complemento (plug-in) para intercambiar contenidos sociales cuando los usuarios deciden dejar abierta la sesi\u00f3n.<\/li><\/ul><p><strong><span style=\"color: #003366;\">4. \u00bfQu\u00e9 cookies instala esta web?<\/span><\/strong><\/p><p class=\"p1\">En ATTRIM Group creemos que el principio de transparencia debe ser uno de los elementos vertebradores en la relaci\u00f3n con nuestros usuarios y de nuestros clientes con sus usuarios. Por ello, informamos de la utilizaci\u00f3n de todas las cookies, tanto propias como de terceros y otras tecnolog\u00edas similares, utilizadas en esta web, incluso las exentas ante la posibilidad de que, alguna de ellas, tenga finalidades polivalentes no exentas:<\/p><table class=\"t1\" cellspacing=\"0\" cellpadding=\"0\"><tbody><tr><td class=\"td1\" valign=\"middle\"><p class=\"p12\">Nombre<\/p><\/td><td class=\"td2\" valign=\"middle\"><p class=\"p12\">Titularidad<\/p><\/td><td class=\"td3\" valign=\"middle\"><p class=\"p12\">Caducidad<\/p><\/td><td class=\"td4\" valign=\"middle\"><p class=\"p12\">Finalidad<\/p><\/td><\/tr><tr><td class=\"td5\" valign=\"middle\"><p class=\"p13\">cookieyes-consent<\/p><\/td><td class=\"td6\" valign=\"middle\"><p class=\"p13\">Propia<\/p><\/td><td class=\"td7\" valign=\"middle\"><p class=\"p13\">24 horas<\/p><\/td><td class=\"td8\" valign=\"middle\"><p class=\"p13\">Permite gestionar el consentimiento RGPD a la instalaci\u00f3n de cookies<\/p><\/td><\/tr><tr><td class=\"td9\" valign=\"middle\"><p class=\"p13\">NID<\/p><\/td><td class=\"td10\" valign=\"middle\"><p class=\"p13\">.google.com<\/p><\/td><td class=\"td11\" valign=\"middle\"><p class=\"p13\">6 meses<\/p><\/td><td class=\"td12\" valign=\"middle\"><p class=\"p13\">Se utiliza para recopilar estad\u00edsticas del sitio web y rastrear las tasas de conversi\u00f3n y la personalizaci\u00f3n de anuncios de Google.<\/p><\/td><\/tr><tr><td class=\"td13\" valign=\"middle\"><p class=\"p13\">_Secure-3PAPISID<\/p><\/td><td class=\"td14\" valign=\"middle\"><p class=\"p13\">.google.com<\/p><\/td><td class=\"td15\" valign=\"middle\"><p class=\"p13\">3 meses<\/p><\/td><td class=\"td16\" valign=\"middle\"><p class=\"p13\">Se utiliza con fines de segmentaci\u00f3n para crear un perfil de los intereses de los visitantes de la web con el fin de mostrar publicidad de Google relevante y personalizada.<\/p><\/td><\/tr><tr><td class=\"td17\" valign=\"middle\"><p class=\"p13\">_Secure-3PSID<\/p><\/td><td class=\"td18\" valign=\"middle\"><p class=\"p13\">.google.com<\/p><\/td><td class=\"td19\" valign=\"middle\"><p class=\"p13\">1 a\u00f1o<\/p><\/td><td class=\"td20\" valign=\"middle\"><p class=\"p13\">Se utiliza para mostrar anuncios m\u00e1s relevantes a los intereses del usuario<\/p><\/td><\/tr><tr><td class=\"td5\" valign=\"middle\"><p class=\"p13\">_Secure-3PSIDCC<\/p><\/td><td class=\"td6\" valign=\"middle\"><p class=\"p13\">.google.com<\/p><\/td><td class=\"td7\" valign=\"middle\"><p class=\"p13\">1 a\u00f1o<\/p><\/td><td class=\"td8\" valign=\"middle\"><p class=\"p13\">Se utiliza para mostrar anuncios m\u00e1s relevantes a los intereses del usuario<\/p><\/td><\/tr><tr><td class=\"td17\" valign=\"middle\"><p class=\"p13\">_Secure-3PSIDTS<\/p><\/td><td class=\"td18\" valign=\"middle\"><p class=\"p13\">.google.com<\/p><\/td><td class=\"td19\" valign=\"middle\"><p class=\"p13\">1 a\u00f1o<\/p><\/td><td class=\"td20\" valign=\"middle\"><p class=\"p13\">Se utiliza para mostrar anuncios m\u00e1s relevantes a los intereses del usuario<\/p><\/td><\/tr><tr><td class=\"td1\" valign=\"middle\"><p class=\"p13\">PHPSESSID<\/p><\/td><td class=\"td2\" valign=\"middle\"><p class=\"p13\">Propia<\/p><\/td><td class=\"td3\" valign=\"middle\"><p class=\"p13\">24 horas<\/p><\/td><td class=\"td4\" valign=\"middle\"><p class=\"p13\">Cookie de sesi\u00f3n<\/p><\/td><\/tr><tr><td class=\"td17\" valign=\"top\"><p class=\"p13\">bscookie<\/p><\/td><td class=\"td18\" valign=\"middle\"><p class=\"p13\">linkedin.com<\/p><\/td><td class=\"td19\" valign=\"middle\"><p class=\"p13\">2 a\u00f1os<\/p><\/td><td class=\"td20\" valign=\"middle\"><p class=\"p13\">Cookie de LinkedIn para identificaci\u00f3n del navegador del usuario<\/p><\/td><\/tr><tr><td class=\"td5\" valign=\"top\"><p class=\"p13\">lang<\/p><\/td><td class=\"td6\" valign=\"middle\"><p class=\"p13\">linkedin.com<\/p><\/td><td class=\"td7\" valign=\"middle\"><p class=\"p13\">2 a\u00f1os<\/p><\/td><td class=\"td8\" valign=\"middle\"><p class=\"p13\">Cookie de LinkedIn para identificar el idioma del usuario<\/p><\/td><\/tr><\/tbody><\/table><p class=\"p1\">Esta web utiliza:<\/p><ul class=\"ul1\"><li class=\"li7\">cookies propias necesarias para el correcto funcionamiento de alguno de nuestros servicios, como es el caso de para permitir el uso continuado de la sesi\u00f3n de usuario registrado (Si se rechaza, el usuario puede ser expulsado de la sesi\u00f3n intermitentemente).<\/li><li class=\"li7\">cookies de terceros para recopilar informaci\u00f3n sobre la experiencia de navegaci\u00f3n de los usuarios en la web, as\u00ed como ofrecer funciones de redes sociales (LinkedIn) y analizar el tr\u00e1fico de la web perteneciente a ATTRIM Group.<\/li><\/ul><p><strong><span style=\"color: #003366;\">5. \u00bfC\u00f3mo puedo administrar las cookies?<\/span><\/strong><\/p><p class=\"p1\">Puede administrar las cookies en la configuraci\u00f3n de esta web desde el aviso de primera capa de cookies en la primera navegaci\u00f3n anterior a su aceptaci\u00f3n.<\/p><p class=\"p1\">Siempre puede configurar, permitir o bloquear las cookies, as\u00ed como borrar sus datos de navegaci\u00f3n (incluidas las cookies) a trav\u00e9s de sus navegadores. La configuraci\u00f3n de los navegadores puede variar seg\u00fan el desarrollador y la versi\u00f3n, por ello, para administrar las cookies debe consultar la configuraci\u00f3n correspondiente dentro de su navegador. Tenga en cuenta que, si acepta las cookies de terceros, deber\u00e1 eliminarlas desde las opciones del navegador.<\/p><p class=\"p1\">La mayor\u00eda de los navegadores indican c\u00f3mo configurar su navegador para que no acepte cookies, para que le notifique cada vez que reciba una nueva cookie, as\u00ed como para desactivarlas completamente. Para controlar qu\u00e9 uso quiere que se haga de su informaci\u00f3n, puede configurar el navegador de su terminal en la forma que estime m\u00e1s conveniente para Ud.<\/p><p class=\"p1\">En todo caso, le hacemos notar que, si se desactivan las cookies t\u00e9cnicas y\/o de funcionamiento, la calidad de la p\u00e1gina web puede disminuir o puede que cueste m\u00e1s identificarle.<\/p><p class=\"p1\">Le indicamos los siguientes enlaces, donde podr\u00e1 encontrar m\u00e1s informaci\u00f3n sobre la configuraci\u00f3n de cookies en los diferentes navegadores:<\/p><ul class=\"ul1\"><li class=\"li1\"><span class=\"s1\"><a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647\"><span class=\"s3\">Chrome<\/span><\/a><\/span><\/li><li class=\"li1\"><span class=\"s1\"><a href=\"https:\/\/support.google.com\/chrome\/answer\/114662?hl=es&amp;rd=1\"><span class=\"s3\">Chrome para Android<\/span><\/a><\/span><\/li><li class=\"li1\"><span class=\"s1\"><a href=\"https:\/\/support.microsoft.com\/es-es\/products\/internet-explorer\"><span class=\"s3\">Explorer<\/span><\/a><\/span><\/li><li class=\"li1\"><span class=\"s1\"><a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\"><span class=\"s3\">Firefox<\/span><\/a><\/span><\/li><li class=\"li1\"><span class=\"s1\"><a href=\"https:\/\/support.apple.com\/kb\/ph5042?locale=en_US\"><span class=\"s3\">Safari <\/span><\/a><\/span><\/li><li class=\"li1\"><span class=\"s1\"><a href=\"https:\/\/support.apple.com\/kb\/ph5042?locale=en_US\"><span class=\"s3\">Safari para IOS <\/span><\/a><\/span><\/li><li class=\"li1\"><span class=\"s1\"><a href=\"https:\/\/privacy.microsoft.com\/en-us\/windows-10-microsoft-edge-and-privacy\"><span class=\"s3\">Windows 10: Microsoft Edge<\/span><\/a><\/span><\/li><\/ul><p class=\"p1\">ATTRIM Group actualizar\u00e1 los anteriores enlaces proporcionados en esta Pol\u00edtica de Cookies de forma regular. Sin embargo, es posible que, en algunos momentos, \u00e9stos no correspondan con la \u00faltima versi\u00f3n publicada por el desarrollador de cada navegador.<\/p><p class=\"p1\">Existen tambi\u00e9n algunos recursos de utilidad que ofrecen informaci\u00f3n detallada sobre los tipos de cookies, c\u00f3mo se utilizan y c\u00f3mo puede administrar sus preferencias de cookies en <a href=\"http:\/\/www.allaboutcookies.org\/\">About Cookies o en All About Cookies. <\/a><\/p><p class=\"p1\">Si desea tener un mayor control sobre la instalaci\u00f3n de cookies, puede instalar programas o complementos a su navegador, conocidos como herramientas de \u201cDo Not Track\u201d, que le permitir\u00e1n escoger aquellas cookies que desea permitir.<\/p><p><strong><span style=\"color: #003366;\">6. \u00bfQu\u00e9 responsabilidades asumimos?<\/span><\/strong><\/p><p class=\"p1\">Los navegadores web son las herramientas encargadas de almacenar las cookies y, es desde estos sitios desde donde debe efectuar su derecho a eliminaci\u00f3n o desactivaci\u00f3n de \u00e9stas. ATTRIM Group no puede garantizar el correcto o incorrecto tratamiento de las cookies por parte de los mencionados navegadores.<\/p><p class=\"p1\">En algunos casos es necesario instalar cookies para que el navegador no olvide su decisi\u00f3n de no aceptaci\u00f3n de estas.<\/p><p class=\"p1\">Para cualquier duda o consulta acerca de esta Pol\u00edtica de Cookies no dude en comunicarse con nosotros a trav\u00e9s de nuestro formulario de contacto.<\/p><p><strong><span style=\"color: #003366;\">7. V\u00ednculos a servicios de terceros.<\/span><\/strong><\/p><p class=\"p1\">Algunos de los servicios prestados por la web perteneciente a ATTRIM Group pueden contener v\u00ednculos a aplicaciones, servicios, herramientas y sitios web de terceros, que Ud. puede utilizar conjuntamente a aplicaciones, servicios, herramientas y sitios web de terceros que no se encuentran vinculados en modo alguno a ATTRIM Group, como, por ejemplo, LinkedIn.<\/p><p class=\"p1\">ATTRIM Group no es responsable de la seguridad ni de la transparencia en la informaci\u00f3n sobre su privacidad aportada a los usuarios por terceros.<\/p><p class=\"p1\">Le recomendamos revisar las pol\u00edticas de privacidad y uso de cookies de las aplicaciones, redes sociales y webs de servicios que utiliza de forma habitual.<\/p><p><strong><span style=\"color: #003366;\">8. \u00daltima actualizaci\u00f3n.<\/span><\/strong><\/p><p class=\"p1\">Esta Pol\u00edtica de Cookies podr\u00e1 ser modificada siempre que se produzcan cambios en la configuraci\u00f3n y\/o utilizaci\u00f3n de estas. Con objeto de mantener la m\u00e1xima transparencia con el usuario, ATTRIM Group mantendr\u00e1 siempre publicada la versi\u00f3n actualizada en esta web haciendo constar su fecha de actualizaci\u00f3n al final de esta p\u00e1gina.<\/p><p class=\"p1\">Si identifica alguna cookie no informada puede ponerse en contacto con nosotros a trav\u00e9s de nuestro <a href=\"https:\/\/www.dataieanalytics.com\/en\/contacto\/\"><span class=\"s4\">formulario de contacto<\/span><\/a> y procederemos a identificar la cookie y a su declaraci\u00f3n.<\/p><p class=\"p1\">\u00daltima actualizaci\u00f3n.<\/p><p class=\"p1\">22\/10\/24<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21826c7 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con-boxed wcf-starter-animations-none e-con e-parent\" data-id=\"21826c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bb345a8 e-flex e-con-boxed wcf-starter-animations-none e-con e-child\" data-id=\"bb345a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0a257d2 e-con-full e-flex wcf-starter-animations-none e-con e-child\" data-id=\"0a257d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ece548b elementor-widget__width-initial elementor-widget-mobile__width-inherit wcf-starter-animations-none wcf-t-animation-none elementor-widget elementor-widget-wcf--title\" data-id=\"ece548b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;bottom&quot;,&quot;data-duration&quot;:0.75,&quot;fade-offset&quot;:40,&quot;wcf_starter_animations&quot;:&quot;none&quot;,&quot;wcf_anim_duration&quot;:1000,&quot;wcf_anim_delay&quot;:0,&quot;wcf_anim_ease&quot;:&quot;ease&quot;,&quot;wcf_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;ease&quot;:&quot;power2.out&quot;}\" data-widget_type=\"wcf--title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"wcf--title\">Conoce los casos de \u00e9xito detr\u00e1s DATAIE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-acfcae9 e-con-full e-flex wcf-starter-animations-none e-con e-child\" data-id=\"acfcae9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-419fce0 e-con-full e-flex wcf-starter-animations-none e-con e-child\" data-id=\"419fce0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;bottom&quot;,&quot;data-duration&quot;:0.75,&quot;fade-offset&quot;:40,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;ease&quot;:&quot;power2.out&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea4c420 elementor-widget elementor-widget-wcf--sassly-button\" data-id=\"ea4c420\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;on-scroll&quot;:&quot;1&quot;,&quot;fade-from&quot;:&quot;bottom&quot;,&quot;data-duration&quot;:0.75,&quot;fade-offset&quot;:40,&quot;delay&quot;:0.15,&quot;ease&quot;:&quot;power2.out&quot;}\" data-widget_type=\"wcf--sassly-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wc-btn-wrapper style-3\">\r\n\t                        <a href=\"https:\/\/www.dataieanalytics.com\/en\/contact\/\" class=\"wc-btn-primary btn-text-flip\">\r\n                    <span data-text=\"Saber m\u00e1s\">\r\n                        Saber m\u00e1s                    <\/span>\r\n\t\t\t                        <\/a>\r\n\t                <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b84b7a2 e-con-full e-flex wcf-starter-animations-none e-con e-child\" data-id=\"b84b7a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;wcf_enable_cursor_hover_effect_text&quot;:&quot;View&quot;,&quot;wcf-animation&quot;:&quot;none&quot;,&quot;wcf_pin_breakpoint&quot;:&quot;mobile&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c5548b wcf-starter-animations-none elementor-widget elementor-widget-wcf--image\" data-id=\"0c5548b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wcf-animation&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;data-duration&quot;:0.75,&quot;fade-offset&quot;:40,&quot;wcf_starter_animations&quot;:&quot;none&quot;,&quot;wcf_anim_duration&quot;:1000,&quot;wcf_anim_delay&quot;:0,&quot;wcf_anim_ease&quot;:&quot;ease&quot;,&quot;wcf-image-animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;ease&quot;:&quot;power2.out&quot;}\" data-widget_type=\"wcf--image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wcf--image\">\r\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2.png\" class=\"attachment-full size-full wp-image-21011\" alt=\"\" srcset=\"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2.png 2000w, https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-350x263.png 350w, https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-300x225.png 300w, https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1024x768.png 1024w, https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-768x576.png 768w, https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1536x1152.png 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de cookies Con car\u00e1cter previo a la navegaci\u00f3n a trav\u00e9s de esta web, Ud. habr\u00e1 tenido la opci\u00f3n de autorizar el uso de todas o algunas cookies, o de rechazarlas o configurarlas mediante la informaci\u00f3n disponible en el aviso de cookies. En todo caso, le recordamos que Ud. puede rechazar las cookies en cualquier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-21659","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de cookies - DAT\u00c2IE Sustainability Analytics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies - DAT\u00c2IE Sustainability Analytics\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de cookies Con car\u00e1cter previo a la navegaci\u00f3n a trav\u00e9s de esta web, Ud. habr\u00e1 tenido la opci\u00f3n de autorizar el uso de todas o algunas cookies, o de rechazarlas o configurarlas mediante la informaci\u00f3n disponible en el aviso de cookies. En todo caso, le recordamos que Ud. puede rechazar las cookies en cualquier [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"DAT\u00c2IE Sustainability Analytics\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T11:33:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1024x768.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de cookies - DAT\u00c2IE Sustainability Analytics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dataieanalytics.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dataie2-1024x768.png\",\"datePublished\":\"2024-09-24T11:45:32+00:00\",\"dateModified\":\"2025-07-22T11:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dataieanalytics.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dataie2-1024x768.png\",\"contentUrl\":\"https:\\\/\\\/www.dataieanalytics.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/dataie2-1024x768.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/en\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.dataieanalytics.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/#website\",\"url\":\"https:\\\/\\\/www.dataieanalytics.com\\\/\",\"name\":\"DAT\u00c2IE Sustainability Analytics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dataieanalytics.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/#organization\",\"name\":\"DAT\u00c2IE Sustainability Analytics\",\"url\":\"https:\\\/\\\/www.dataieanalytics.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dataieanalytics.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/DataieLOGO.png\",\"contentUrl\":\"https:\\\/\\\/www.dataieanalytics.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/DataieLOGO.png\",\"width\":1223,\"height\":366,\"caption\":\"DAT\u00c2IE Sustainability Analytics\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dataieanalytics.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dataieanalytics\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies - DAT\u00c2IE Sustainability Analytics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/","og_locale":"en_GB","og_type":"article","og_title":"Pol\u00edtica de cookies - DAT\u00c2IE Sustainability Analytics","og_description":"Pol\u00edtica de cookies Con car\u00e1cter previo a la navegaci\u00f3n a trav\u00e9s de esta web, Ud. habr\u00e1 tenido la opci\u00f3n de autorizar el uso de todas o algunas cookies, o de rechazarlas o configurarlas mediante la informaci\u00f3n disponible en el aviso de cookies. En todo caso, le recordamos que Ud. puede rechazar las cookies en cualquier [&hellip;]","og_url":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/","og_site_name":"DAT\u00c2IE Sustainability Analytics","article_modified_time":"2025-07-22T11:33:37+00:00","og_image":[{"url":"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1024x768.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/","url":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/","name":"Pol\u00edtica de cookies - DAT\u00c2IE Sustainability Analytics","isPartOf":{"@id":"https:\/\/www.dataieanalytics.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/#primaryimage"},"image":{"@id":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1024x768.png","datePublished":"2024-09-24T11:45:32+00:00","dateModified":"2025-07-22T11:33:37+00:00","breadcrumb":{"@id":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/#primaryimage","url":"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1024x768.png","contentUrl":"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/09\/dataie2-1024x768.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dataieanalytics.com\/en\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.dataieanalytics.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.dataieanalytics.com\/#website","url":"https:\/\/www.dataieanalytics.com\/","name":"DAT\u00c2IE Sustainability Analytics","description":"","publisher":{"@id":"https:\/\/www.dataieanalytics.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dataieanalytics.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.dataieanalytics.com\/#organization","name":"DAT\u00c2IE Sustainability Analytics","url":"https:\/\/www.dataieanalytics.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.dataieanalytics.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/05\/DataieLOGO.png","contentUrl":"https:\/\/www.dataieanalytics.com\/wp-content\/uploads\/2024\/05\/DataieLOGO.png","width":1223,"height":366,"caption":"DAT\u00c2IE Sustainability Analytics"},"image":{"@id":"https:\/\/www.dataieanalytics.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/dataieanalytics"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/pages\/21659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/comments?post=21659"}],"version-history":[{"count":25,"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/pages\/21659\/revisions"}],"predecessor-version":[{"id":22848,"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/pages\/21659\/revisions\/22848"}],"wp:attachment":[{"href":"https:\/\/www.dataieanalytics.com\/en\/wp-json\/wp\/v2\/media?parent=21659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}